{"id":202,"count":1,"description":"","link":"https:\/\/valloni.ch\/de\/tag\/rofr-de\/","name":"ROFR","slug":"rofr-de","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ROFR Archives - Valloni<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ROFR Archives - Valloni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/valloni.ch\/de\/tag\/rofr-de\/\" \/>\n<meta property=\"og:site_name\" content=\"Valloni\" \/>\n<meta property=\"og:image\" content=\"https:\/\/valloni.ch\/wp-content\/uploads\/2025\/08\/Valloni_negative_NoPayoff_RGB-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ROFR Archives - Valloni","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"ROFR Archives - Valloni","og_url":"https:\/\/valloni.ch\/de\/tag\/rofr-de\/","og_site_name":"Valloni","og_image":[{"width":2560,"height":1810,"url":"https:\/\/valloni.ch\/wp-content\/uploads\/2025\/08\/Valloni_negative_NoPayoff_RGB-scaled.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/valloni.ch\/de\/tag\/rofr-de\/","url":"https:\/\/valloni.ch\/de\/tag\/rofr-de\/","name":"ROFR Archives - Valloni","isPartOf":{"@id":"https:\/\/valloni.ch\/#website"},"breadcrumb":{"@id":"https:\/\/valloni.ch\/de\/tag\/rofr-de\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/valloni.ch\/de\/tag\/rofr-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/valloni.ch\/de\/"},{"@type":"ListItem","position":2,"name":"ROFR"}]},{"@type":"WebSite","@id":"https:\/\/valloni.ch\/#website","url":"https:\/\/valloni.ch\/","name":"Valloni","description":"Attorneys at Law LLC","publisher":{"@id":"https:\/\/valloni.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/valloni.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/valloni.ch\/#organization","name":"VALLONI Attorneys at Law","url":"https:\/\/valloni.ch\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/valloni.ch\/#\/schema\/logo\/image\/","url":"https:\/\/valloni.ch\/wp-content\/uploads\/2025\/08\/Valloni_negative_NoPayoff_RGB-scaled.png","contentUrl":"https:\/\/valloni.ch\/wp-content\/uploads\/2025\/08\/Valloni_negative_NoPayoff_RGB-scaled.png","width":2560,"height":1810,"caption":"VALLONI Attorneys at Law"},"image":{"@id":"https:\/\/valloni.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/lucienvalloni?s=21&t=gsdDE--5p_Q9GnLZfeueXg","https:\/\/www.linkedin.com\/company\/valloni-attorneys-at-law\/?viewAsMember=true"]}]}},"_links":{"self":[{"href":"https:\/\/valloni.ch\/de\/wp-json\/wp\/v2\/tags\/202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/valloni.ch\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/valloni.ch\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/valloni.ch\/de\/wp-json\/wp\/v2\/posts?tags=202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}